{"id":10276,"date":"2024-04-02T10:56:26","date_gmt":"2024-04-02T08:56:26","guid":{"rendered":"https:\/\/uic.se\/?post_type=bolag&#038;p=10276"},"modified":"2024-04-02T10:56:26","modified_gmt":"2024-04-02T08:56:26","slug":"arendra","status":"publish","type":"bolag","link":"https:\/\/uic.se\/en\/bolag\/arendra\/","title":{"rendered":"Arendra"},"content":{"rendered":"\n<p>Arendra provides a manager app and web tool for systematic risk assessment in work health, motivation and performance. It gives the employer predictability, financial incentives, courage to act responsibly and an organizational overview for HR and management.<\/p>\n","protected":false},"featured_media":0,"template":"","industry":[28],"bolag-program":[34],"bolag-demo-day":[],"class_list":["post-10276","bolag","type-bolag","status-publish","hentry","industry-life-science-health-care","bolag-program-uic-accelerator"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arendra - Uppsala Innovation Centre<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arendra - Uppsala Innovation Centre\" \/>\n<meta property=\"og:description\" content=\"Arendra provides a manager app and web tool for systematic risk assessment in work health, motivation and performance. It gives the employer predictability, financial incentives, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uic.se\/bolag\/arendra\/\" \/>\n<meta property=\"og:site_name\" content=\"Uppsala Innovation Centre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uic.se\\\/bolag\\\/arendra\\\/\",\"url\":\"https:\\\/\\\/uic.se\\\/bolag\\\/arendra\\\/\",\"name\":\"Arendra - Uppsala Innovation Centre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uic.se\\\/#website\"},\"datePublished\":\"2024-04-02T08:56:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uic.se\\\/bolag\\\/arendra\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uic.se\\\/bolag\\\/arendra\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uic.se\\\/bolag\\\/arendra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uic.se\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UIC-Bolags\",\"item\":\"https:\\\/\\\/uic.se\\\/bolag\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arendra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uic.se\\\/#website\",\"url\":\"https:\\\/\\\/uic.se\\\/\",\"name\":\"Uppsala Innovation Centre\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uic.se\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uic.se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uic.se\\\/#organization\",\"name\":\"Uppsala Innovation Centre\",\"alternateName\":\"UIC\",\"url\":\"https:\\\/\\\/uic.se\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uic.se\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uic.se\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/UIC_logo_vertical_white.png\",\"contentUrl\":\"https:\\\/\\\/uic.se\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/UIC_logo_vertical_white.png\",\"width\":1436,\"height\":800,\"caption\":\"Uppsala Innovation Centre\"},\"image\":{\"@id\":\"https:\\\/\\\/uic.se\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arendra - Uppsala Innovation Centre","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Arendra - Uppsala Innovation Centre","og_description":"Arendra provides a manager app and web tool for systematic risk assessment in work health, motivation and performance. It gives the employer predictability, financial incentives, [&hellip;]","og_url":"https:\/\/uic.se\/bolag\/arendra\/","og_site_name":"Uppsala Innovation Centre","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uic.se\/bolag\/arendra\/","url":"https:\/\/uic.se\/bolag\/arendra\/","name":"Arendra - Uppsala Innovation Centre","isPartOf":{"@id":"https:\/\/uic.se\/#website"},"datePublished":"2024-04-02T08:56:26+00:00","breadcrumb":{"@id":"https:\/\/uic.se\/bolag\/arendra\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uic.se\/bolag\/arendra\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/uic.se\/bolag\/arendra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uic.se\/en\/"},{"@type":"ListItem","position":2,"name":"UIC-Bolags","item":"https:\/\/uic.se\/bolag\/"},{"@type":"ListItem","position":3,"name":"Arendra"}]},{"@type":"WebSite","@id":"https:\/\/uic.se\/#website","url":"https:\/\/uic.se\/","name":"Uppsala Innovation Centre","description":"","publisher":{"@id":"https:\/\/uic.se\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uic.se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/uic.se\/#organization","name":"Uppsala Innovation Centre","alternateName":"UIC","url":"https:\/\/uic.se\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uic.se\/#\/schema\/logo\/image\/","url":"https:\/\/uic.se\/wp-content\/uploads\/2024\/11\/UIC_logo_vertical_white.png","contentUrl":"https:\/\/uic.se\/wp-content\/uploads\/2024\/11\/UIC_logo_vertical_white.png","width":1436,"height":800,"caption":"Uppsala Innovation Centre"},"image":{"@id":"https:\/\/uic.se\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"industry":[{"value":28,"label":"Life Science\/Health care"}],"bolag-program":[{"value":34,"label":"UIC Accelerator"}]},"featured_image_src_large":false,"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/bolag\/10276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/bolag"}],"about":[{"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/types\/bolag"}],"wp:attachment":[{"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/media?parent=10276"}],"wp:term":[{"taxonomy":"industry","embeddable":true,"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/industry?post=10276"},{"taxonomy":"bolag-program","embeddable":true,"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/bolag-program?post=10276"},{"taxonomy":"demo-day","embeddable":true,"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/bolag-demo-day?post=10276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}