{"id":7132,"date":"2022-01-05T15:38:52","date_gmt":"2022-01-05T13:38:52","guid":{"rendered":"https:\/\/uic.se\/bolag\/mm18-medical\/"},"modified":"2024-02-08T12:00:26","modified_gmt":"2024-02-08T10:00:26","slug":"mm18-medical","status":"publish","type":"bolag","link":"https:\/\/uic.se\/en\/bolag\/mm18-medical\/","title":{"rendered":"Cellda MM18 Medical"},"content":{"rendered":"<p>Utvecklar en programvara, Cellda\u00ae, f\u00f6r bildanalys av v\u00e4vnadsprover, med inriktning p\u00e5 prostatacancer. Tekniken kan ers\u00e4tta patologens manuella, tidskr\u00e4vande och subjektiva cancerdiagnostik med s\u00e4ker, snabb och objektiv datoriserad diagnostik.<\/p>\n","protected":false},"featured_media":0,"template":"","industry":[84],"bolag-program":[34],"bolag-demo-day":[],"class_list":["post-7132","bolag","type-bolag","status-publish","hentry","industry-life-science-halsa-en","bolag-program-uic-accelerator"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cellda MM18 Medical - Uppsala Innovation Centre<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cellda MM18 Medical - Uppsala Innovation Centre\" \/>\n<meta property=\"og:description\" content=\"Utvecklar en programvara, Cellda\u00ae, f\u00f6r bildanalys av v\u00e4vnadsprover, med inriktning p\u00e5 prostatacancer. Tekniken kan ers\u00e4tta patologens manuella, tidskr\u00e4vande och subjektiva cancerdiagnostik med s\u00e4ker, snabb och [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uic.se\/en\/bolag\/mm18-medical\/\" \/>\n<meta property=\"og:site_name\" content=\"Uppsala Innovation Centre\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-08T10:00:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uic.se\\\/en\\\/bolag\\\/mm18-medical\\\/\",\"url\":\"https:\\\/\\\/uic.se\\\/en\\\/bolag\\\/mm18-medical\\\/\",\"name\":\"Cellda MM18 Medical - Uppsala Innovation Centre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uic.se\\\/#website\"},\"datePublished\":\"2022-01-05T13:38:52+00:00\",\"dateModified\":\"2024-02-08T10:00:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uic.se\\\/en\\\/bolag\\\/mm18-medical\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uic.se\\\/en\\\/bolag\\\/mm18-medical\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uic.se\\\/en\\\/bolag\\\/mm18-medical\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uic.se\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UIC-Bolags\",\"item\":\"https:\\\/\\\/uic.se\\\/bolag\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cellda MM18 Medical\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uic.se\\\/#website\",\"url\":\"https:\\\/\\\/uic.se\\\/\",\"name\":\"Uppsala Innovation Centre\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uic.se\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uic.se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uic.se\\\/#organization\",\"name\":\"Uppsala Innovation Centre\",\"alternateName\":\"UIC\",\"url\":\"https:\\\/\\\/uic.se\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uic.se\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uic.se\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/UIC_logo_vertical_white.png\",\"contentUrl\":\"https:\\\/\\\/uic.se\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/UIC_logo_vertical_white.png\",\"width\":1436,\"height\":800,\"caption\":\"Uppsala Innovation Centre\"},\"image\":{\"@id\":\"https:\\\/\\\/uic.se\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cellda MM18 Medical - Uppsala Innovation Centre","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Cellda MM18 Medical - Uppsala Innovation Centre","og_description":"Utvecklar en programvara, Cellda\u00ae, f\u00f6r bildanalys av v\u00e4vnadsprover, med inriktning p\u00e5 prostatacancer. Tekniken kan ers\u00e4tta patologens manuella, tidskr\u00e4vande och subjektiva cancerdiagnostik med s\u00e4ker, snabb och [&hellip;]","og_url":"https:\/\/uic.se\/en\/bolag\/mm18-medical\/","og_site_name":"Uppsala Innovation Centre","article_modified_time":"2024-02-08T10:00:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uic.se\/en\/bolag\/mm18-medical\/","url":"https:\/\/uic.se\/en\/bolag\/mm18-medical\/","name":"Cellda MM18 Medical - Uppsala Innovation Centre","isPartOf":{"@id":"https:\/\/uic.se\/#website"},"datePublished":"2022-01-05T13:38:52+00:00","dateModified":"2024-02-08T10:00:26+00:00","breadcrumb":{"@id":"https:\/\/uic.se\/en\/bolag\/mm18-medical\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uic.se\/en\/bolag\/mm18-medical\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/uic.se\/en\/bolag\/mm18-medical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uic.se\/en\/"},{"@type":"ListItem","position":2,"name":"UIC-Bolags","item":"https:\/\/uic.se\/bolag\/"},{"@type":"ListItem","position":3,"name":"Cellda MM18 Medical"}]},{"@type":"WebSite","@id":"https:\/\/uic.se\/#website","url":"https:\/\/uic.se\/","name":"Uppsala Innovation Centre","description":"","publisher":{"@id":"https:\/\/uic.se\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uic.se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/uic.se\/#organization","name":"Uppsala Innovation Centre","alternateName":"UIC","url":"https:\/\/uic.se\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uic.se\/#\/schema\/logo\/image\/","url":"https:\/\/uic.se\/wp-content\/uploads\/2024\/11\/UIC_logo_vertical_white.png","contentUrl":"https:\/\/uic.se\/wp-content\/uploads\/2024\/11\/UIC_logo_vertical_white.png","width":1436,"height":800,"caption":"Uppsala Innovation Centre"},"image":{"@id":"https:\/\/uic.se\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"industry":[{"value":84,"label":"Life science\/h\u00e4lsa"}],"bolag-program":[{"value":34,"label":"UIC Accelerator"}]},"featured_image_src_large":false,"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/bolag\/7132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/bolag"}],"about":[{"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/types\/bolag"}],"wp:attachment":[{"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/media?parent=7132"}],"wp:term":[{"taxonomy":"industry","embeddable":true,"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/industry?post=7132"},{"taxonomy":"bolag-program","embeddable":true,"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/bolag-program?post=7132"},{"taxonomy":"demo-day","embeddable":true,"href":"https:\/\/uic.se\/en\/wp-json\/wp\/v2\/bolag-demo-day?post=7132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}